{"id":254,"date":"2020-02-24T13:08:57","date_gmt":"2020-02-24T13:08:57","guid":{"rendered":"https:\/\/demosites.io\/zelle-gb\/?page_id=143"},"modified":"2025-02-12T02:04:14","modified_gmt":"2025-02-12T02:04:14","slug":"0227d-home","status":"publish","type":"page","link":"https:\/\/siouxamerica.com\/","title":{"rendered":"Home"},"content":{"rendered":"\n<div id=\"wp-block-themeisle-blocks-advanced-columns-d26b6b4e\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-center\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-bc8f6b49\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<h1 class=\"wp-block-heading has-text-align-center has-white-color has-text-color\">Bienvenidos a SIOUX America<br>Real Estate<\/h1>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-button-group-2dde628f\" class=\"wp-block-themeisle-blocks-button-group collapse-mobile wp-block-buttons align-center\">\n<div id=\"wp-block-themeisle-blocks-button-9b0883a7\" class=\"wp-block-themeisle-blocks-button wp-block-button\"><a href=\"\" target=\"_self\" rel=\"noopener noreferrer\" class=\"wp-block-button__link\"><i class=\"fas fa-fw fa-plane-departure margin-right\"><\/i><span>Special Deals<\/span><\/a><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-button-754057ce\" class=\"wp-block-themeisle-blocks-button wp-block-button\"><a href=\"\" target=\"_self\" rel=\"noopener noreferrer\" class=\"wp-block-button__link\"><i class=\"fas fa-fw fa-book-open margin-right\"><\/i><span>Travel Blog<\/span><\/a><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-button-571269f2\" class=\"wp-block-themeisle-blocks-button wp-block-button\"><a href=\"\" target=\"_self\" rel=\"noopener noreferrer\" class=\"wp-block-button__link\"><i class=\"far fa-fw fa-envelope margin-right\"><\/i><span>Contact Us<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"focus\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-collapsedRows-layout has-vertical-center ticss-c00aadba\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-1c31b2a5\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<div id=\"wp-block-themeisle-blocks-advanced-columns-58edafaa\" class=\"wp-block-themeisle-blocks-advanced-columns has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-center\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-f09cc82a\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<h2 id=\"wp-block-themeisle-blocks-advanced-heading-20b96fb6\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-20b96fb6\">Tu aliado de confianza en la compra, venta y arrendamiento de propiedades residenciales y comerciales en diversos pa\u00edses.<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Asesor\u00eda en todo el proceso por parte de nuestro equipo de expertos.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-columns-71420444\" class=\"wp-block-themeisle-blocks-advanced-columns has-3-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-collapsedRows-layout has-vertical-top\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-df5299ae\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<div id=\"wp-block-themeisle-blocks-font-awesome-icons-3d48a50f\" class=\"wp-block-themeisle-blocks-font-awesome-icons\"><span class=\"wp-block-themeisle-blocks-font-awesome-icons-container\"><i class=\"fas fa-business-time\"><\/i><\/span><\/div>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 id=\"wp-block-themeisle-blocks-advanced-heading-d5158682\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-d5158682\">COMPRA Y VENTA<\/h3>\n\n\n\n<p class=\"has-text-align-center has-link-color-color has-text-color\">If a City Break is a flight + accommodation, why would you need an agency? Because we offer you accommodation at a discounted price.<br><\/p>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-b2e0b556\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<div id=\"wp-block-themeisle-blocks-font-awesome-icons-70cdee2b\" class=\"wp-block-themeisle-blocks-font-awesome-icons\"><span class=\"wp-block-themeisle-blocks-font-awesome-icons-container\"><i class=\"fas fa-users\"><\/i><\/span><\/div>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 id=\"wp-block-themeisle-blocks-advanced-heading-b5682b5a\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-b5682b5a\"> ASESOR\u00cdA Y ACOMPA\u00d1AMIENTO<\/h3>\n\n\n\n<p class=\"has-text-align-center has-link-color-color has-text-color\">Reconnect with nature, feel its freedom and enjoy the peace and quiet. See places untouched by the human hand and reflect on nature\u2019s beauty.<\/p>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-3c90b8e8\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<div id=\"wp-block-themeisle-blocks-font-awesome-icons-28d12b67\" class=\"wp-block-themeisle-blocks-font-awesome-icons\"><span class=\"wp-block-themeisle-blocks-font-awesome-icons-container\"><i class=\"fas fa-house-user\"><\/i><\/span><\/div>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 id=\"wp-block-themeisle-blocks-advanced-heading-5677d91c\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-5677d91c\"> CONFIANZA<\/h3>\n\n\n\n<p class=\"has-text-align-center has-link-color-color has-text-color\">You\u2019ll certainly remember the traditional villages, incredibly beautiful landscapes with white mountains and huge ski areas.<br><\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-columns-d8142c6e\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-unset has-light-bg\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-5c38f6b1\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<h2 id=\"wp-block-themeisle-blocks-advanced-heading-8a6fcd5c\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-8a6fcd5c\">Discover OUr Special Deal Packages<\/h2>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-primary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/siouxamerica.com\/blog\/\">Explore more!<\/a><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"about\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-collapsedRows-layout has-vertical-center ticss-c00aadba\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-16ea63fb\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<div id=\"wp-block-themeisle-blocks-advanced-columns-0d998e8f\" class=\"wp-block-themeisle-blocks-advanced-columns has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-center\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-959aef23\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<h2 id=\"wp-block-themeisle-blocks-advanced-heading-a1a28b67\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-a1a28b67\">Discover the World with Us!<\/h2>\n\n\n\n<p class=\"has-text-align-center has-nv-text-dark-bg-color has-text-color has-link-color wp-elements-78c9668a5635697d94ab16d3f55f67a5\">For those who want vacations done the right way<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-columns-fa27132c\" class=\"wp-block-themeisle-blocks-advanced-columns has-3-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-collapsedRows-layout has-vertical-top\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-dfb15c39\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<h3 id=\"wp-block-themeisle-blocks-advanced-heading-e0a4cde3\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-e0a4cde3\"> 12 Years Of Successful Vacation Planning<\/h3>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-fc7c8a56\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<p id=\"wp-block-themeisle-blocks-advanced-heading-1539f9d4\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-1539f9d4\">On a constantly changing tourism market, it can sometimes be difficult to find a trusted partner. And when you analyze the services of an agency, you have to take into account several aspects \u2013 experience, diversity, prices, opinions of other tourists.<\/p>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-f2e9cefc\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<p id=\"wp-block-themeisle-blocks-advanced-heading-83b86ff7\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-83b86ff7\">With over 12 years of experience, we offer both \u201ctraditional\u201d and some more special destinations. Whether you want a vacation at the sea or skiing, a circuit in the country or abroad, an escape from the daily or a team building, <\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-columns-05ad31b0\" class=\"wp-block-themeisle-blocks-advanced-columns has-3-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-collapsedRows-layout has-vertical-top\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-a8074228\" class=\"wp-block-themeisle-blocks-advanced-column has-light-bg\">\n<div id=\"wp-block-themeisle-blocks-font-awesome-icons-2884ebd9\" class=\"wp-block-themeisle-blocks-font-awesome-icons\"><span class=\"wp-block-themeisle-blocks-font-awesome-icons-container\"><i class=\"fas fa-phone-volume\"><\/i><\/span><\/div>\n\n\n\n<h3 id=\"wp-block-themeisle-blocks-advanced-heading-27492df9\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-27492df9\">Always available for assistance<\/h3>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-0938aa77\" class=\"wp-block-themeisle-blocks-advanced-column has-light-bg\">\n<div id=\"wp-block-themeisle-blocks-font-awesome-icons-d90e3a99\" class=\"wp-block-themeisle-blocks-font-awesome-icons\"><span class=\"wp-block-themeisle-blocks-font-awesome-icons-container\"><i class=\"fas fa-dollar-sign\"><\/i><\/span><\/div>\n\n\n\n<h3 id=\"wp-block-themeisle-blocks-advanced-heading-f9f79608\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-f9f79608\">Affordable exotic vacations<\/h3>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-e8925615\" class=\"wp-block-themeisle-blocks-advanced-column has-dark-bg\">\n<div id=\"wp-block-themeisle-blocks-font-awesome-icons-c7f29eb0\" class=\"wp-block-themeisle-blocks-font-awesome-icons\"><span class=\"wp-block-themeisle-blocks-font-awesome-icons-container\"><i class=\"fas fa-user\"><\/i><\/span><\/div>\n\n\n\n<h3 id=\"wp-block-themeisle-blocks-advanced-heading-81b89b6c\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-81b89b6c\">Customer-First Service<\/h3>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"team\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-collapsedRows-layout has-vertical-center ticss-c00aadba\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-97d0da3f\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<div id=\"wp-block-themeisle-blocks-advanced-columns-ebe7dd95\" class=\"wp-block-themeisle-blocks-advanced-columns has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-center\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-0fbf1da8\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<h2 id=\"wp-block-themeisle-blocks-advanced-heading-ed13c6ae\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-ed13c6ae\">Meet our Travel Experts<\/h2>\n\n\n\n<p class=\"has-text-align-center\">They are the people working to provide you the best experiences.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-columns-0e844709\" class=\"wp-block-themeisle-blocks-advanced-columns has-3-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-collapsedRows-layout has-vertical-top\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-6c381990\" class=\"wp-block-themeisle-blocks-advanced-column\"><div class=\"wp-block-image is-resized is-style-circle-mask\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert1.jpg\" alt=\"\" class=\"wp-image-91\" style=\"width:96px\"\/><\/figure>\n<\/div>\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 id=\"wp-block-themeisle-blocks-advanced-heading-ad54c2ec\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-ad54c2ec\"> TIMOTHY SPRAY<\/h5>\n\n\n\n<p class=\"has-text-align-center has-neve-text-color-color has-text-color has-small-font-size\">City Break Expert<\/p>\n\n\n\n<p class=\"has-text-align-center has-neve-text-color-color has-text-color\">If a City Break is a flight + accommodation, why would you need an agency? Because we offer you accommodation at a discounted price.<br><\/p>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-769eff47\" class=\"wp-block-themeisle-blocks-advanced-column\"><div class=\"wp-block-image is-resized is-style-circle-mask\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert2.jpg\" alt=\"\" class=\"wp-image-92\" style=\"width:96px\" srcset=\"https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert2.jpg 350w, https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert2-300x300.jpg 300w, https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert2-150x150.jpg 150w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 id=\"wp-block-themeisle-blocks-advanced-heading-dbc11db4\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-dbc11db4\"> ASHLEY SIMMONS<\/h5>\n\n\n\n<p class=\"has-text-align-center has-neve-text-color-color has-text-color has-small-font-size\">Nature Trips Expert<\/p>\n\n\n\n<p class=\"has-text-align-center has-neve-text-color-color has-text-color\">Reconnect with nature, feel its freedom and enjoy the peace and quiet. See places untouched by the human hand and reflect on nature\u2019s beauty.<\/p>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-d8577cf2\" class=\"wp-block-themeisle-blocks-advanced-column\"><div class=\"wp-block-image is-resized is-style-circle-mask\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert3.jpg\" alt=\"\" class=\"wp-image-93\" style=\"width:96px\" srcset=\"https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert3.jpg 350w, https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert3-300x300.jpg 300w, https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert3-150x150.jpg 150w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 id=\"wp-block-themeisle-blocks-advanced-heading-a92ba5ed\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-a92ba5ed\"> TONY GARCIA<\/h5>\n\n\n\n<p class=\"has-text-align-center has-neve-text-color-color has-text-color has-small-font-size\">Exotic Destinations Expert<\/p>\n\n\n\n<p class=\"has-text-align-center has-neve-text-color-color has-text-color\">You\u2019ll certainly remember the traditional villages, incredibly beautiful landscapes with white mountains and huge ski areas.<br><\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"testimonials\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-collapsedRows-layout has-vertical-center ticss-c00aadba has-light-bg\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-d0fbfc0a\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<div id=\"wp-block-themeisle-blocks-advanced-columns-f32a2609\" class=\"wp-block-themeisle-blocks-advanced-columns has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-center\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-3567d86b\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<h2 id=\"wp-block-themeisle-blocks-advanced-heading-d5f71f32\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-d5f71f32\">Hear from our Travellers<\/h2>\n\n\n\n<p class=\"has-text-align-center has-nv-text-dark-bg-color has-text-color has-link-color wp-elements-a3e2f3e85730f63ee0c37c86804b4b6f\">Our extensive expertise will make sure that yours is a SUCCESS STORY!<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-columns-8085ff1f\" class=\"wp-block-themeisle-blocks-advanced-columns has-3-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-collapsedRows-layout has-vertical-top\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-574a647b\" class=\"wp-block-themeisle-blocks-advanced-column has-light-bg\"><div class=\"wp-block-image is-resized is-style-circle-mask\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert3.jpg\" alt=\"\" class=\"wp-image-93\" style=\"width:96px\" srcset=\"https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert3.jpg 350w, https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert3-300x300.jpg 300w, https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert3-150x150.jpg 150w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center has-nv-dark-bg-color has-text-color\" style=\"font-size:15px\">A wonderful experience, attentive staff and always at the disposal of tourists \/ clients. During the stay, we had only beautiful things, attentive staff, impeccable accommodation, food and beverages, from varied categories, for all tastes. Performances and evening entertainment both on the beach at the ocean and at the pools during the day.<br><\/p>\n\n\n\n<h2 id=\"wp-block-themeisle-blocks-advanced-heading-ad840ea5\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-ad840ea5\"> David Lorem<\/h2>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-a0d46b3c\" class=\"wp-block-themeisle-blocks-advanced-column has-light-bg\"><div class=\"wp-block-image is-resized is-style-circle-mask\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert2.jpg\" alt=\"\" class=\"wp-image-92\" style=\"width:96px\" srcset=\"https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert2.jpg 350w, https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert2-300x300.jpg 300w, https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert2-150x150.jpg 150w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center has-nv-dark-bg-color has-text-color\" style=\"font-size:15px\">I had an unexpectedly successful holiday. The choice of hotel was very good, being one that offers everything you need for a pleasant holiday. The staff was very receptive, kind and attentive. The food was great for everyone. Transport to the most important points of interest was free of charge. Thank you Neve Agency for a wonderful holiday.<br><\/p>\n\n\n\n<h2 id=\"wp-block-themeisle-blocks-advanced-heading-b4e159ca\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-b4e159ca\"> Linda Guthrie<\/h2>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-e487f041\" class=\"wp-block-themeisle-blocks-advanced-column has-light-bg\"><div class=\"wp-block-image is-resized is-style-circle-mask\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert3.jpg\" alt=\"\" class=\"wp-image-93\" style=\"width:96px\" srcset=\"https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert3.jpg 350w, https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert3-300x300.jpg 300w, https:\/\/siouxamerica.com\/wp-content\/uploads\/2019\/02\/zelle-expert3-150x150.jpg 150w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center has-nv-dark-bg-color has-text-color\" style=\"font-size:15px\">A wonderful experience, attentive staff and always at the disposal of tourists \/ clients. During the stay, we had only beautiful things, attentive staff, impeccable accommodation, food and beverages, from varied categories, for all tastes. Performances and evening entertainment both on the beach at the ocean and at the pools during the day.<br><\/p>\n\n\n\n<h2 id=\"wp-block-themeisle-blocks-advanced-heading-8e2102b8\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-8e2102b8\"> David Lorem<\/h2>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-columns-50b2912d\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-collapsedRows-layout has-vertical-center ticss-c00aadba\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-11e36bd7\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<div id=\"wp-block-themeisle-blocks-advanced-columns-bdc459a3\" class=\"wp-block-themeisle-blocks-advanced-columns has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-center\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-426b8888\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<h2 id=\"wp-block-themeisle-blocks-advanced-heading-2209d6b2\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-2209d6b2\">Travel Blog Tips<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Be inspired by our blog<\/p>\n\n\n\n<div class=\"wp-block-query is-layout-flow wp-block-query-is-layout-flow\"><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"contact\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-unset\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-c81f51d3\" class=\"wp-block-themeisle-blocks-advanced-column has-dark-bg\">\n<h2 class=\"wp-block-heading has-text-align-center has-neve-text-color-color has-text-color\">Env\u00edanos tu solicitud!<\/h2>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color\">We are here for you, 24\/7, to help you and reply within the hour.<\/p>\n\n\n\n<div id=\"wp-block-themeisle-blocks-form-aed2787f\" class=\"wp-block-themeisle-blocks-form\" data-option-name=\"bf9b28ff82ce323187abc5d0feb0d8f07ecd8436_aed2787f\"><form class=\"otter-form__container\">\n<div id=\"wp-block-themeisle-blocks-form-input-ae306451\" class=\"wp-block-themeisle-blocks-form-input\"><label for=\"wp-block-themeisle-blocks-form-input-ae306451-input\" class=\"otter-form-input-label\"><span class=\"otter-form-input-label__label\">Email<\/span><span class=\"required\">*<\/span><\/label><input type=\"email\" id=\"wp-block-themeisle-blocks-form-input-ae306451-input\" required class=\"otter-form-input\"\/><\/div>\n\n\n<div class=\"protection\" aria-hidden=\"true\"><input type=\"hidden\" id=\"wp-block-themeisle-blocks-form-aed2787f_nonce_field\" name=\"wp-block-themeisle-blocks-form-aed2787f_nonce_field\" value=\"c6648f5dfb\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/index.php\/wp-json\/wp\/v2\/pages\/254\" \/><input class=\"o-anti-bot\" type=\"checkbox\"><\/div>\n\n\n<div id=\"wp-block-themeisle-blocks-form-input-137d24ec\" class=\"wp-block-themeisle-blocks-form-input is-style-o-c-half\"><label for=\"wp-block-themeisle-blocks-form-input-137d24ec-input\" class=\"otter-form-input-label\"><span class=\"otter-form-input-label__label\">Number of Adults<\/span><\/label><input type=\"number\" id=\"wp-block-themeisle-blocks-form-input-137d24ec-input\" class=\"otter-form-input\"\/><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-form-input-1bc81e76\" class=\"wp-block-themeisle-blocks-form-input is-style-o-c-half\"><label for=\"wp-block-themeisle-blocks-form-input-1bc81e76-input\" class=\"otter-form-input-label\"><span class=\"otter-form-input-label__label\">Number of Children<\/span><\/label><input type=\"number\" id=\"wp-block-themeisle-blocks-form-input-1bc81e76-input\" class=\"otter-form-input\"\/><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-form-input-2ecedbce\" class=\"wp-block-themeisle-blocks-form-input is-style-o-c-half\"><label for=\"wp-block-themeisle-blocks-form-input-2ecedbce-input\" class=\"otter-form-input-label\"><span class=\"otter-form-input-label__label\">Trip Budget<\/span><\/label><input type=\"text\" id=\"wp-block-themeisle-blocks-form-input-2ecedbce-input\" placeholder=\"e.g. $1000\" class=\"otter-form-input\"\/><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-form-input-186d00f9\" class=\"wp-block-themeisle-blocks-form-input is-style-o-c-half\"><label for=\"wp-block-themeisle-blocks-form-input-186d00f9-input\" class=\"otter-form-input-label\"><span class=\"otter-form-input-label__label\">Travel Dates<\/span><\/label><input type=\"date\" id=\"wp-block-themeisle-blocks-form-input-186d00f9-input\" class=\"otter-form-input\"\/><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-form-textarea-56ad0433\" class=\"wp-block-themeisle-blocks-form-textarea\"><label for=\"wp-block-themeisle-blocks-form-textarea-56ad0433-input\" class=\"otter-form-textarea-label\"><span class=\"otter-form-textarea-label__label\">Message<\/span><\/label><textarea id=\"wp-block-themeisle-blocks-form-textarea-56ad0433-input\" rows=\"10\" class=\"otter-form-textarea-input\"><\/textarea><\/div>\n\n\n\n<p class=\"has-extra-small-font-size\">You agree to receive email communication from us by submitting this form and understand that your contact information will be stored with us.<\/p>\n<div class=\"wp-block-button\"><button class=\"wp-block-button__link\" type=\"submit\">Submit<\/button><\/div><\/form><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-columns-acdd57b3\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-unset\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-aa6f8a0a\" class=\"wp-block-themeisle-blocks-advanced-column\"><\/div>\n<\/div><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-columns-d2b3b50b\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-4-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-collapsedRows-layout has-vertical-unset has-dark-bg\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-34178fa7\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<div id=\"wp-block-themeisle-blocks-font-awesome-icons-b2e502b6\" class=\"wp-block-themeisle-blocks-font-awesome-icons\"><span class=\"wp-block-themeisle-blocks-font-awesome-icons-container\"><i class=\"far fa-map\"><\/i><\/span><\/div>\n\n\n\n<p class=\"has-text-align-center has-text-color\" style=\"color:#939393;font-size:14px\"> AGENCY LOCATION<br>20 Povernei, District 1, Downtown Bucharest&nbsp; <\/p>\n\n\n\n<p class=\"has-text-align-center has-text-color\" style=\"color:#939393;font-size:14px\">  MON-FRI: 10 \u2013 17<br>SAT: 10 \u2013 14 &nbsp; <\/p>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-f47e1f6c\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<div id=\"wp-block-themeisle-blocks-font-awesome-icons-135a5b66\" class=\"wp-block-themeisle-blocks-font-awesome-icons\"><span class=\"wp-block-themeisle-blocks-font-awesome-icons-container\"><i class=\"fas fa-envelope\"><\/i><\/span><\/div>\n\n\n\n<p class=\"has-text-align-center has-text-color\" style=\"color:#939393;font-size:14px\">GET OUR LATEST OFFERS<br><\/p>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-ff2e198d\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<div id=\"wp-block-themeisle-blocks-font-awesome-icons-5d962d6e\" class=\"wp-block-themeisle-blocks-font-awesome-icons\"><span class=\"wp-block-themeisle-blocks-font-awesome-icons-container\"><i class=\"fas fa-phone-square\"><\/i><\/span><\/div>\n\n\n\n<p class=\"has-text-align-center has-text-color\" style=\"color:#939393;font-size:14px\"> 24\/7 ASSISTANCE<br>+40 332 548 987 <\/p>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-c483a70c\" class=\"wp-block-themeisle-blocks-advanced-column has-dark-bg\">\n<div id=\"wp-block-themeisle-blocks-button-group-80ddb8f3\" class=\"wp-block-themeisle-blocks-button-group wp-block-buttons align-center\">\n<div id=\"wp-block-themeisle-blocks-button-fdd96c26\" class=\"wp-block-themeisle-blocks-button wp-block-button\"><a href=\"\" target=\"_self\" rel=\"noopener noreferrer\" class=\"wp-block-button__link\"><i class=\"fab fa-fw fa-facebook-f\"><\/i><\/a><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-button-ebdcdc08\" class=\"wp-block-themeisle-blocks-button wp-block-button\"><a href=\"\" target=\"_self\" rel=\"noopener noreferrer\" class=\"wp-block-button__link\"><i class=\"fab fa-fw fa-twitter\"><\/i><\/a><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-button-f58142b5\" class=\"wp-block-themeisle-blocks-button wp-block-button\"><a href=\"\" target=\"_self\" rel=\"noopener noreferrer\" class=\"wp-block-button__link\"><i class=\"fab fa-fw fa-linkedin-in\"><\/i><\/a><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-button-fb88105d\" class=\"wp-block-themeisle-blocks-button wp-block-button\"><a href=\"\" target=\"_self\" rel=\"noopener noreferrer\" class=\"wp-block-button__link\"><i class=\"fab fa-fw fa-behance\"><\/i><\/a><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-button-10eca286\" class=\"wp-block-themeisle-blocks-button wp-block-button\"><a href=\"\" target=\"_self\" rel=\"noopener noreferrer\" class=\"wp-block-button__link\"><i class=\"fab fa-fw fa-dribbble\"><\/i><\/a><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center\"> \u00a9 2023&nbsp;<a href=\"https:\/\/themeisle.com\/\">Neve Agency<\/a> <\/p>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"neve_meta_sidebar":"full-width","neve_meta_container":"contained","neve_meta_enable_content_width":"on","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"_kadence_starter_templates_imported_post":false,"footnotes":""},"class_list":["post-254","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/siouxamerica.com\/index.php\/wp-json\/wp\/v2\/pages\/254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siouxamerica.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/siouxamerica.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/siouxamerica.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/siouxamerica.com\/index.php\/wp-json\/wp\/v2\/comments?post=254"}],"version-history":[{"count":9,"href":"https:\/\/siouxamerica.com\/index.php\/wp-json\/wp\/v2\/pages\/254\/revisions"}],"predecessor-version":[{"id":300,"href":"https:\/\/siouxamerica.com\/index.php\/wp-json\/wp\/v2\/pages\/254\/revisions\/300"}],"wp:attachment":[{"href":"https:\/\/siouxamerica.com\/index.php\/wp-json\/wp\/v2\/media?parent=254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}